{"id":58014,"date":"2019-11-18T04:52:01","date_gmt":"2019-11-18T02:52:01","guid":{"rendered":"https:\/\/wordpress-237795-1094026.cloudwaysapps.com\/a-propos-nous\/"},"modified":"2025-04-08T14:13:16","modified_gmt":"2025-04-08T12:13:16","slug":"about-us","status":"publish","type":"page","link":"https:\/\/nefertiti-eg.com\/fr\/about-us\/","title":{"rendered":"\u00c0 propos nous"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"58014\" class=\"elementor elementor-58014 elementor-1977\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ba061f6 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ba061f6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:70047,&quot;url&quot;:&quot;https:\\\/\\\/nefertiti-eg.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Render-2.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-329f49e0\" data-id=\"329f49e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6a12dac4 elementor-invisible\" data-id=\"6a12dac4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f26e3b elementor-widget elementor-widget-text-editor\" data-id=\"3f26e3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: left;\">Le d\u00e9but de notre histoire <\/h2><p style=\"text-align: left;\">Notre mission a d\u00e9but\u00e9 en 2002 et a r\u00e9ussi \u00e0 devenir l&rsquo;une des principales entreprises de fabrication dans le domaine des huiles essentielles et plantes aromatiques naturelles, des produits cosm\u00e9tiques et des herbes. Nous vous souhaitons la bienvenue dans notre entreprise\u2026 \u00abNefertiti for Natural Oils &amp; Herbs\u00bb<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b6dced4 elementor-widget elementor-widget-image\" data-id=\"6b6dced4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"510\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/01\/Nefertiti_Essential-Oils_Aroma-Oils.jpg\" class=\"attachment-large size-large wp-image-59987\" alt=\"\" srcset=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/01\/Nefertiti_Essential-Oils_Aroma-Oils.jpg 900w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/01\/Nefertiti_Essential-Oils_Aroma-Oils-130x74.jpg 130w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/01\/Nefertiti_Essential-Oils_Aroma-Oils-700x397.jpg 700w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/01\/Nefertiti_Essential-Oils_Aroma-Oils-300x170.jpg 300w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/01\/Nefertiti_Essential-Oils_Aroma-Oils-768x435.jpg 768w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/01\/Nefertiti_Essential-Oils_Aroma-Oils-600x340.jpg 600w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/01\/Nefertiti_Essential-Oils_Aroma-Oils-150x85.jpg 150w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-919fd4d elementor-widget elementor-widget-text-editor\" data-id=\"919fd4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Nous avons commenc\u00e9 \u00e0 construire notre entreprise avec une petite ferme dans la province d&rsquo;Al Fayoum, \u00e0 130 km du Caire, en \u00c9gypte, et avec notre premi\u00e8re boutique \u00e0 Hurghada, apr\u00e8s seulement 2 ans, nous avons \u00e9t\u00e9 ravis de commencer notre expansion. Avec maintenant 7 boutiques autour de Hurghada et Charm el-Cheikh, et des boutiques officielles en Bi\u00e9lorussie et en Ukraine, nous continuons \u00e0 cro\u00eetre rapidement et notre objectif est d&rsquo;\u00eatre disponible dans de nombreux autres pays dans les ann\u00e9es \u00e0 venir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2363978\" data-id=\"2363978\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-419cdae4 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"419cdae4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:65670,&quot;url&quot;:&quot;https:\\\/\\\/nefertiti-eg.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/barnabel-2.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5c2e2c68\" data-id=\"5c2e2c68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dda59ab elementor-widget elementor-widget-text-editor\" data-id=\"3dda59ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Notre ferme<\/h2><p>Bienvenue dans notre ferme! Al Fayoum est une grande oasis dans le d\u00e9sert, qui abrite la r\u00e9serve naturelle du lac Qaroun et l&rsquo;une des zones agricoles les plus riches d&rsquo;\u00c9gypte.<br \/>Comme nous avons commenc\u00e9 avec une petite ferme, cela signifiait que nous achetions et importions des semences d&rsquo;autres fermes pour nos produits. En 2009, nous avons d\u00e9cid\u00e9 de nous concentrer sur l&rsquo;agrandissement de notre ferme afin de pouvoir b\u00e9n\u00e9ficier de r\u00e9coltes plus importantes, en utilisant les meilleures m\u00e9thodes de plantation traditionnelles \u00c9gyptiennes et des engrais naturels pour des produits sains et de haute qualit\u00e9.<\/p><p><img decoding=\"async\" class=\" wp-image-65676 alignleft\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/bottles-botanicals-2-300x216.png\" alt=\"\" width=\"349\" height=\"252\" title=\"\" srcset=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/bottles-botanicals-2-300x216.png 300w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/bottles-botanicals-2-130x94.png 130w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/bottles-botanicals-2-150x108.png 150w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/bottles-botanicals-2.png 420w\" sizes=\"(max-width: 349px) 100vw, 349px\" \/><\/p><h2>Notre technologie<\/h2><p>La technologie \u00e9volue toujours rapidement et pour cette raison, nous nous effor\u00e7ons de garder une longueur d&rsquo;avance. Nous avons sur le terrain, une \u00e9quipe d&rsquo;ing\u00e9nieurs et de chercheurs comp\u00e9tents qui se tiennent constamment au courant des meilleures proc\u00e9dures, mises \u00e0 niveau et des machines pour produire des produits sains et de haute qualit\u00e9 dans notre usine. Notre technologie moderne de pressage \u00e0 froid garantit une production constante d&rsquo;huiles naturelles pures. Pour certains de nos produits, nous utilisons \u00e9galement la technologie de distillation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1badae62\" data-id=\"1badae62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ae00ca2 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ae00ca2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ab3f7d3\" data-id=\"6ab3f7d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3559449e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3559449e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ff55459\" data-id=\"ff55459\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36df7113 elementor-widget elementor-widget-image\" data-id=\"36df7113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/elementor\/thumbs\/Logo-about-us-ot333c85t2l0nduz3d6arip1n5hun6lsxofkhjnt1s.png\" title=\"Logo &#8211; about us\" alt=\"Logo - about us\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-16e0fdf7\" data-id=\"16e0fdf7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2aadaafd elementor-widget elementor-widget-text-editor\" data-id=\"2aadaafd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\">Marque Nefertiti<\/span> <\/h2><p>Notre marque est inspir\u00e9e et fi\u00e8rement nomm\u00e9e d&rsquo;apr\u00e8s la c\u00e9l\u00e8bre reine \u00e9gyptienne antique. Nefertiti, de son nom traduit par \u00abLa belle femme est venue\u00bb, \u00e9tait une ic\u00f4ne de puissance et de beaut\u00e9. Ainsi, repr\u00e9sentant parfaitement l\u2019ambition de notre entreprise et son d\u00e9vouement envers vous. Notre responsabilit\u00e9 est d\u2019offrir \u00e0 nos clients estim\u00e9s, des produits dont les r\u00e9sultats r\u00e9pondent aux attentes les plus \u00e9lev\u00e9es dont vous \u00eates royalement dignes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-36a722a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36a722a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4abb91eb\" data-id=\"4abb91eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ec76451 elementor-widget elementor-widget-text-editor\" data-id=\"6ec76451\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\">La beaut\u00e9 au naturel, pour vous<\/span><\/h2><p>Nous avons un objectif et une mission simples\u2026 vous faire vous sentir incroyable \u00e0 l&rsquo;int\u00e9rieur comme \u00e0 l&rsquo;ext\u00e9rieur de votre corps! Il est important d&rsquo;assurer une bonne sant\u00e9, en particulier avec une pollution atmosph\u00e9rique plus nocive et des choix alimentaires al\u00e9atoires. Nos produits naturels vous aideront \u00e0 prendre soin de votre sant\u00e9 et de votre bien-\u00eatre, favorisant ainsi un mode de vie plus heureux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-be164e3\" data-id=\"be164e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c077b78 elementor-widget elementor-widget-image\" data-id=\"4c077b78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"294\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Flax-Points-2-300x294.png\" class=\"attachment-medium size-medium wp-image-65836\" alt=\"\" srcset=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Flax-Points-2-300x294.png 300w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Flax-Points-2-130x128.png 130w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Flax-Points-2-700x687.png 700w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Flax-Points-2-600x589.png 600w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Flax-Points-2-150x147.png 150w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Flax-Points-2.png 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-65a489a6 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65a489a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d07713c\" data-id=\"d07713c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59cfa538 elementor-widget elementor-widget-image\" data-id=\"59cfa538\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"271\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/bottles-on-shelf-300x271.png\" class=\"attachment-medium size-medium wp-image-65814\" alt=\"\" srcset=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/bottles-on-shelf-300x271.png 300w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/bottles-on-shelf-130x117.png 130w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/bottles-on-shelf-150x135.png 150w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/bottles-on-shelf.png 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-708f9ae1\" data-id=\"708f9ae1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d45085 elementor-widget elementor-widget-text-editor\" data-id=\"7d45085\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\">Nos emballages<\/span><\/h2><p>Nos flacons certifi\u00e9s abritent parfaitement vos produits, disponibles en verre de couleur marron ou en plastique transparent m\u00e9dical garanti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-287ca0da elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"287ca0da\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-206b7091\" data-id=\"206b7091\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-457943a0 elementor-widget elementor-widget-text-editor\" data-id=\"457943a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\">Notre promesse de qualit\u00e9<\/span><\/h2><p>Alors que nous aspirons \u00e0 \u00eatre une entreprise unique et de confiance, nous sommes ravis de partager avec vous nos certificats approuv\u00e9s ISO (Organisation internationale de normalisation) et CoA (certificat d&rsquo;analyse), pour votre tranquillit\u00e9 d&rsquo;esprit. Nous nous engageons \u00e0 vous d\u00e9livrer des produits 100% naturels et de la plus haute qualit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-12e17a7c\" data-id=\"12e17a7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d30aeb7 elementor-widget elementor-widget-image\" data-id=\"3d30aeb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Certificated-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-65824\" alt=\"\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8b8a84c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b8a84c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a09b509\" data-id=\"a09b509\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be6b132 elementor-widget elementor-widget-image\" data-id=\"be6b132\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2025\/04\/BRSM-1-1.jpg\" title=\"\" alt=\"\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9a46015 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9a46015\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ce53b1b\" data-id=\"ce53b1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45f3ea2 elementor-widget elementor-widget-image\" data-id=\"45f3ea2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2025\/04\/iso-1-1-1.png\" title=\"\" alt=\"\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f2e2d8 elementor-widget elementor-widget-text-editor\" data-id=\"4f2e2d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>Quality Management System.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d1c0f1b\" data-id=\"d1c0f1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2dd92f elementor-widget elementor-widget-image\" data-id=\"e2dd92f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2025\/04\/iso4-1-1.png\" title=\"\" alt=\"\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18a3445 elementor-widget elementor-widget-text-editor\" data-id=\"18a3445\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>Environmental management system.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2d7f99a\" data-id=\"2d7f99a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2f47fa elementor-widget elementor-widget-image\" data-id=\"e2f47fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2025\/04\/iso2-1-1.png\" title=\"\" alt=\"\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b1c7bc elementor-widget elementor-widget-text-editor\" data-id=\"2b1c7bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>Occupational Health &amp; Safety.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4b8d8b0\" data-id=\"4b8d8b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b36e05a elementor-widget elementor-widget-image\" data-id=\"b36e05a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2025\/04\/iso3-1-1.png\" title=\"\" alt=\"\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49ee636 elementor-widget elementor-widget-text-editor\" data-id=\"49ee636\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>Food Safety Management System.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-355a1847 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"355a1847\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78b553d1\" data-id=\"78b553d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-430aa6c8 elementor-widget elementor-widget-image\" data-id=\"430aa6c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/\u0417\u043d\u0430\u043a_\u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u044f.png\" class=\"attachment-medium size-medium wp-image-65726\" alt=\"\" srcset=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/\u0417\u043d\u0430\u043a_\u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u044f.png 250w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/\u0417\u043d\u0430\u043a_\u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u044f-130x130.png 130w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/\u0417\u043d\u0430\u043a_\u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u044f-150x150.png 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-74efb90d\" data-id=\"74efb90d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54d9d0ed elementor-widget elementor-widget-text-editor\" data-id=\"54d9d0ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une marque de certification sur un produit commercial indique l&rsquo;existence d&rsquo;une norme ou d&rsquo;un r\u00e8glement de produit accept\u00e9 et une all\u00e9gation selon laquelle le fabricant a v\u00e9rifi\u00e9 la conformit\u00e9 \u00e0 ces normes ou r\u00e8glements.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-68cfdaa7 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68cfdaa7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-26a80db6\" data-id=\"26a80db6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4641e6a5 elementor-widget elementor-widget-text-editor\" data-id=\"4641e6a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">The Eurasian Conformity mark (EAC, Russian: \u0415\u0432\u0440\u0430\u0437\u0438\u0439\u0441\u043a\u043e\u0435 \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u0435 (\u0415\u0410\u0421) ) certifies that our products conform to all technical regulations of the Eurasian Customs Union.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a68ca75\" data-id=\"3a68ca75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3915b96f elementor-widget elementor-widget-image\" data-id=\"3915b96f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/EAC.png\" class=\"attachment-medium size-medium wp-image-65732\" alt=\"\" srcset=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/EAC.png 250w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/EAC-130x130.png 130w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/EAC-150x150.png 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-68462b02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68462b02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-994d126\" data-id=\"994d126\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41628ca elementor-widget elementor-widget-image\" data-id=\"41628ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Ministry-of-health-_-population.png\" class=\"attachment-medium size-medium wp-image-65738\" alt=\"\" srcset=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Ministry-of-health-_-population.png 250w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Ministry-of-health-_-population-130x130.png 130w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/Ministry-of-health-_-population-150x150.png 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ecf17c1\" data-id=\"5ecf17c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a573bcf elementor-widget elementor-widget-text-editor\" data-id=\"4a573bcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous pouvez trouver nos produits de suppl\u00e9ment nutritionnel sous licence et assur\u00e9s disponibles en pharmacie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-774eb81b elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"774eb81b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-19ae5140\" data-id=\"19ae5140\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-747d627a elementor-widget elementor-widget-text-editor\" data-id=\"747d627a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous sommes fiers de vous offrir des produits certifi\u00e9s 100% naturels, sains et de haute qualit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f5a89bd\" data-id=\"f5a89bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33fd5e2f elementor-widget elementor-widget-image\" data-id=\"33fd5e2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"172\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/certifecate-1.png\" class=\"attachment-medium size-medium wp-image-65762\" alt=\"\" srcset=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/certifecate-1.png 222w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/certifecate-1-130x101.png 130w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/certifecate-1-150x116.png 150w\" sizes=\"(max-width: 222px) 100vw, 222px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-628b7a0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"628b7a0e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-16113e4f\" data-id=\"16113e4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46d11171 elementor-widget elementor-widget-image\" data-id=\"46d11171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/EOST.png\" class=\"attachment-medium size-medium wp-image-65744\" alt=\"\" srcset=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/EOST.png 250w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/EOST-130x130.png 130w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/EOST-150x150.png 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2cb2c37b\" data-id=\"2cb2c37b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bf04c63 elementor-widget elementor-widget-text-editor\" data-id=\"2bf04c63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos ingr\u00e9dients de qualit\u00e9 sont extraits selon des sp\u00e9cifications internationales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45276a87 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45276a87\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5733416e\" data-id=\"5733416e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-746540e1 elementor-widget elementor-widget-spacer\" data-id=\"746540e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57d4cfe7 elementor-widget elementor-widget-text-editor\" data-id=\"57d4cfe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>magasins locaux<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10644db6 elementor-widget elementor-widget-spacer\" data-id=\"10644db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-223538a2 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"223538a2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-617fe1d0\" data-id=\"617fe1d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a5c7476 elementor-widget elementor-widget-text-editor\" data-id=\"5a5c7476\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nefertiti Office<\/strong>\u00a0<\/p><p><strong>Address:<\/strong>\u00a0Al fondok st, Qesm Hurghada, Redsea, Egypt.<br \/><strong>Email:<\/strong>\u00a0customer-care@nefertiti-eg.com<br \/><strong>Phone:<\/strong> +2 01011416292<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3577eb8d\" data-id=\"3577eb8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ec09923 elementor-widget elementor-widget-text-editor\" data-id=\"5ec09923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nefertiti HRG Store (1) <\/strong>\u00a0<\/p><p><strong>Address:\u00a0<\/strong>Al Kawthar District Abu Ashra Street, Hurghada, Red Sea Governorate.<br \/><strong>Email:<\/strong>\u00a0customer-care@nefertiti-eg.com<br \/><strong>Phone:<\/strong>\u00a0+2 01098000767<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2ab136d\" data-id=\"2ab136d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b1eae47 elementor-widget elementor-widget-text-editor\" data-id=\"6b1eae47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nefertiti Palace <strong>HRG <\/strong><strong>(2)<\/strong><\/strong><\/p><p><strong>Address:<\/strong>\u00a0Alkawthar , Air port road , Hurghada , Red Sea.<br \/><strong>Email:<\/strong>\u00a0customer-care@nefertiti-eg.com<br \/><strong>Phone:<\/strong>\u00a0+2 01001576117<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-402d059e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"402d059e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-72926613\" data-id=\"72926613\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6450f80b elementor-widget elementor-widget-text-editor\" data-id=\"6450f80b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nefertiti Sharm El Sheikh<\/strong><\/p><p><strong>Address:<\/strong>\u00a0Nefertiti, Mall, El-salam St, sunny lakes resort, beside ideal standards, No.4, South Sinai Governorate 46911.<br \/><strong>Email:<\/strong>\u00a0customer-care@nefertiti-eg.com<br \/><strong>Phone:<\/strong> +20 114 553 3230<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-32c389ca\" data-id=\"32c389ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63ef17ae elementor-widget elementor-widget-text-editor\" data-id=\"63ef17ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nefertiti Taba<\/strong><\/p><p><strong>Address:<\/strong>\u00a0Hilton Taba, Shop number 4, South Sinai Governorate 46618.<br \/><strong>Email:<\/strong>\u00a0taba@nefertiti-eg.com<br \/><strong>Phone:<\/strong> +20\u00a0155\u00a05671557<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-12cdde5a\" data-id=\"12cdde5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e683897 elementor-widget elementor-widget-text-editor\" data-id=\"e683897\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nefertiti Giza (1)<\/strong><\/p><p><strong>Address:<\/strong> 27 Hadayek El Ahram St, behind Le M\u00e9ridien Pyramids Hotel, Al Remaya Square, Al Haram, Giza Governorate 12561<br \/><strong>Email:<\/strong>\u00a0customer-care@nefertiti-eg.com<br \/><strong>Phone:<\/strong> +2 01011416292<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0ccb5a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0ccb5a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c147c29\" data-id=\"c147c29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84cea62 elementor-widget elementor-widget-text-editor\" data-id=\"84cea62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nefertiti Giza (2)<\/strong><\/p>\n<p><strong>Address:<\/strong>El Sheikh mustafa ismail St, Hadayek Al Ahram-Giza-Egypt<br><strong>Email:<\/strong>&nbsp;customer-care@nefertiti-eg.com<br><strong>Phone:<\/strong>&nbsp;+2 01011416292<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4eb0ad8\" data-id=\"4eb0ad8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a5d698 elementor-widget elementor-widget-text-editor\" data-id=\"3a5d698\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Nefertiti El Qusair Branch\u00a0<\/b><\/p><p><b>Adress<\/b><span style=\"font-weight: 400;\">: Cornish Street in front of el Fardous Fish Restaurant<\/span><\/p><p><b>Phone<\/b><span style=\"font-weight: 400;\">: +2 01011416292<\/span><\/p><p><b>Email<\/b><span style=\"font-weight: 400;\">: customer-care@nefertiti-eg.com<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b493749\" data-id=\"b493749\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70c68c0 elementor-widget elementor-widget-text-editor\" data-id=\"70c68c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Nefertiti Empire\u00a0 (Hurghada)<\/b><\/p><p><b>Adress<\/b><span style=\"font-weight: 400;\">: Legend Compound (Mubarak 2) in front of El Daniel For Leather\u00a0<\/span><\/p><p><b>Phone<\/b><span style=\"font-weight: 400;\">: +2 01011416292<\/span><\/p><p><b>Email<\/b><span style=\"font-weight: 400;\">: customer-care@nefertiti-eg.com<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a26bd04 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a26bd04\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c51b3f9\" data-id=\"4c51b3f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ed420de elementor-widget elementor-widget-text-editor\" data-id=\"3ed420de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Magasins internationaux<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f80543 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f80543\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ca925a\" data-id=\"7ca925a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f83d153 elementor-widget elementor-widget-text-editor\" data-id=\"f83d153\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Nefertiti Dubia<\/strong><\/p><p style=\"text-align: center;\">NEFERTITI PALACE GENERAL TRADING L.L.C<br \/>Address: Garden city building 2, asas properties, street 18, zone 334, Shop number 4, Satwa, Dubai.<\/p><p style=\"text-align: center;\"><strong>Email:<\/strong> dxp@nefertiti-eg.com<br \/><strong>Phone:<\/strong> +971 55 834 3722<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fabd9cf\" data-id=\"fabd9cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fc92d3 elementor-widget elementor-widget-text-editor\" data-id=\"9fc92d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Nefertiti Russia ( Perfumes Only )<\/strong><\/span><\/p><p style=\"text-align: center;\">\u0433. \u0421\u0438\u043c\u0444\u0435\u0440\u043e\u043f\u043e\u043b\u044c \u0415\u0432\u043f\u0430\u0442\u043e\u0440\u0438\u0439\u0441\u043a\u043e\u0435 \u0448. 8, \u0422\u0426 \u00ab\u041c\u0435\u0433\u0430\u043d\u043e\u043c\u00bb \u0422\u0435\u043a\u0441\u0442\u0438\u043b\u044c \u0446\u0435\u043d\u0442\u0440 \u00ab\u041f\u0438\u0440\u0430\u043c\u0438\u0434\u0430\u00bb<br \/>\u0433. \u0421\u0438\u043c\u0444\u0435\u0440\u043e\u043f\u043e\u043b\u044c, \u0443\u043b. \u041a\u0443\u0431\u0430\u043d\u0441\u043a\u0430\u044f 1, \u0422\u0435\u043a\u0441\u0442\u0438\u043b\u044c \u0446\u0435\u043d\u0442\u0440 \u00ab\u041f\u0438\u0440\u0430\u043c\u0438\u0434\u0430\u00bb<br \/><strong>Phone:<\/strong> <a href=\"tel:+79788576855\">+79788576855<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c6cd6fc elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6cd6fc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d55aad5\" data-id=\"d55aad5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a2b28d elementor-widget elementor-widget-text-editor\" data-id=\"7a2b28d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nefertiti Ukraine<\/strong><\/p><p>\u041e\u041e\u041e \u00ab\u0418\u0421\u0418\u0414\u0410 \u042d\u0420\u0410\u00bb\u00a0<br \/><strong>Address: <\/strong>61001, \u0423\u043a\u0440\u0430\u0438\u043d\u0430, \u0425\u0430\u0440\u044c\u043a\u043e\u0432, \u0443\u043b. \u041c\u043e\u043b\u043e\u0447\u043d\u0430\u044f, 11, \u043a\u043e\u0440\u043f\u0443\u0441 5<br \/><strong>Email:<\/strong>\u00a0ukraine@nefertiti-eg.com<br \/><strong>Phone:<\/strong> +38 098 59 300 54<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-95fc5a7\" data-id=\"95fc5a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b56bfe elementor-widget elementor-widget-text-editor\" data-id=\"1b56bfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nefertiti Bosnia<\/strong><\/p><p>\u00ab\u00a0Nefertiti\u00a0\u00bb d.o.o Sarajevo<br \/><strong>Address<\/strong>: ul. Stupska bb, Objekat \u010c-3 br. prostora PP9, Stup, Nukleus, Tibra 2, Sarajevo, Ilid\u017ea<br \/><strong>Email: <\/strong>Bosnia@nefertiti-eg.com<br \/><strong>Phone:<\/strong> +38762661807<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8ca8b40\" data-id=\"8ca8b40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb9776b elementor-widget elementor-widget-text-editor\" data-id=\"cb9776b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Bosnia\u00a0<\/b><\/p><p><b>Address<\/b><span style=\"font-weight: 400;\">: Sarajevo City Center, Second Floor<br \/><\/span><b>Phone:<\/b><span style=\"font-weight: 400;\"> +38762661807<br \/><\/span><b>Email<\/b><span style=\"font-weight: 400;\">: Bosnia@nefertiti-eg.com<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abeedfb elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abeedfb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-04c8b20\" data-id=\"04c8b20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80d2ef0 elementor-widget elementor-widget-text-editor\" data-id=\"80d2ef0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Romania<\/strong><\/p><p><strong>Address:<\/strong>\u00a0Bucharest, District 3, 2 Rotunda Street, building Y1C, room 57<br \/><strong>Email:<\/strong> romania@nefertiti-eg.com<br \/><strong>Phone:<\/strong> +40 720 945 348<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5f7f2d3\" data-id=\"5f7f2d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fad2b4 elementor-widget elementor-widget-text-editor\" data-id=\"7fad2b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong><span style=\"color: #000000;\">Nefertiti Armenia<\/span><\/strong><\/p><p style=\"text-align: center;\">\u0421\u0430\u0441\u0443\u043d\u0446\u0438 \u0414\u0430\u0432\u0438\u0434 58<\/p><p style=\"text-align: center;\"><strong>Location:<\/strong> <a href=\"https:\/\/www.google.com\/maps\/place\/Nefertiti+Armenia\/@40.1545511,44.5181442,17z\/data=!3m1!4b1!4m6!3m5!1s0x406abd94e4e27c7f:0xcaee0ea2de6f5537!8m2!3d40.1545511!4d44.5181442!16s%2Fg%2F11x5__lyxy?entry=ttu&amp;g_ep=EgoyMDI1MDQwMi4xIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">58 Sasuntsi Davit St, Yerevan 0001, Armenia<\/a><br \/><strong>Phone:<\/strong>\u00a0 +374 43 303 304<br \/><strong>Web<\/strong>: <a href=\"https:\/\/www.nefertiti.am\" target=\"_blank\" rel=\"noopener\">www.nefertiti.am<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-01322c4\" data-id=\"01322c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-635d523 elementor-widget elementor-widget-text-editor\" data-id=\"635d523\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Nefertiti Kazakhstan<\/b><\/p><p><b>Address:\u00a0<\/b>Almaty city, Kabdolov street, building 1, Grand park shopping and entertainment center<\/p><p><b>Phone<\/b><span style=\"font-weight: 400;\">:+7 701 536 7888<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f76b33 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f76b33\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-63ff8230\" data-id=\"63ff8230\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-1f89d24e\" data-id=\"1f89d24e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ea169a6 elementor-widget elementor-widget-spacer\" data-id=\"3ea169a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16cef12e elementor-widget elementor-widget-text-editor\" data-id=\"16cef12e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\">Nous sommes \u00e0 votre service<\/h2><p>Nous sommes ravis de vous \u00eatre disponible en 7 langues (anglais, russe, ukrainien, fran\u00e7ais, italien, lituanien, Kazakhstan), soyez assur\u00e9 que vous serez habilement pris en charge par notre \u00e9quipe polyglotte, qui se tient pr\u00eate \u00e0 vous accueillir avec toutes les informations dont vous avez besoin et ainsi r\u00e9pondre \u00e0 toutes vos questions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4abbe39e elementor-widget elementor-widget-image\" data-id=\"4abbe39e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"106\" src=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/anabel-banabas-sig-sml.png\" class=\"attachment-large size-large wp-image-65756\" alt=\"\" srcset=\"https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/anabel-banabas-sig-sml.png 400w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/anabel-banabas-sig-sml-130x34.png 130w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/anabel-banabas-sig-sml-300x80.png 300w, https:\/\/nefertiti-eg.com\/wp-content\/uploads\/2020\/07\/anabel-banabas-sig-sml-150x40.png 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5441579b elementor-widget elementor-widget-spacer\" data-id=\"5441579b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-78caf33e\" data-id=\"78caf33e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9but de notre histoire Notre mission a d\u00e9but\u00e9 en 2002 et a r\u00e9ussi \u00e0 devenir l&rsquo;une des principales entreprises de fabrication dans le domaine des huiles essentielles et plantes aromatiques naturelles, des produits cosm\u00e9tiques et des herbes. Nous vous souhaitons la bienvenue dans notre entreprise\u2026 \u00abNefertiti for Natural Oils &amp; Herbs\u00bb Nous avons commenc\u00e9 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth-no-heading.php","meta":{"footnotes":""},"class_list":["post-58014","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nefertiti-eg.com\/fr\/wp-json\/wp\/v2\/pages\/58014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nefertiti-eg.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nefertiti-eg.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nefertiti-eg.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nefertiti-eg.com\/fr\/wp-json\/wp\/v2\/comments?post=58014"}],"version-history":[{"count":31,"href":"https:\/\/nefertiti-eg.com\/fr\/wp-json\/wp\/v2\/pages\/58014\/revisions"}],"predecessor-version":[{"id":291668,"href":"https:\/\/nefertiti-eg.com\/fr\/wp-json\/wp\/v2\/pages\/58014\/revisions\/291668"}],"wp:attachment":[{"href":"https:\/\/nefertiti-eg.com\/fr\/wp-json\/wp\/v2\/media?parent=58014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}